{"id":6880,"date":"2022-12-26T10:05:55","date_gmt":"2022-12-26T09:05:55","guid":{"rendered":"https:\/\/edusign.fr\/blog\/?p=6880"},"modified":"2022-12-26T10:05:55","modified_gmt":"2022-12-26T09:05:55","slug":"tout-savoir-sur-labondement-cpf-par-lemployeur","status":"publish","type":"post","link":"https:\/\/edusign.com\/fr\/blog\/tout-savoir-sur-labondement-cpf-par-lemployeur\/","title":{"rendered":"Tout savoir sur l\u2019abondement CPF par l\u2019employeur"},"content":{"rendered":"\n<p>Le <strong><a href=\"https:\/\/edusign.fr\/blog\/tout-savoir-sur-le-cpf-son-mode-demploi-et-ses-avantages-en-2022\/\" data-type=\"post\" data-id=\"6667\" target=\"_blank\" rel=\"noopener\">CPF<\/a><\/strong> est un sujet tr\u00e8s r\u00e9guli\u00e8rement abord\u00e9 dans l\u2019actualit\u00e9, en particulier en p\u00e9riode de crise lorsque tout un chacun chercher \u00e0 peaufiner ses comp\u00e9tences professionnelles, ou \u00e0 se former \u00e0 un nouveau poste. Les enjeux des <strong><a href=\"https:\/\/edusign.fr\/blog\/les-organismes-de-formations-professionnel\/\" data-type=\"post\" data-id=\"2071\" target=\"_blank\" rel=\"noopener\">formations professionnelles<\/a><\/strong> sont importants, mais ce qui nous int\u00e9resse ici, c\u2019est surtout la mani\u00e8re dont les comptes CPF sont abond\u00e9s. En d\u2019autres termes : <strong>financ\u00e9s, aliment\u00e9s<\/strong>.&nbsp;<\/p>\n\n\n\n<p>L\u2019employeur est la principale entit\u00e9 proc\u00e9dant \u00e0 ce fameux abondement. Caract\u00e8re obligatoire ou non de l\u2019abondement CPF, mode de fonctionnement ou encore hypoth\u00e8se de l\u2019expiration des droits CPF, nous vous expliquons tout ce qu\u2019il faut savoir \u00e0 ce sujet !<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\">D\u00e9finition du CPF !<\/h2>\n\n\n\n<p>La premi\u00e8re question \u00e0 se poser est la suivante : qu\u2019est-ce r\u00e9ellement que le CPF ? Comment fonctionne-t-il ? \u00c0 qui est-il destin\u00e9 ?<\/p>\n\n\n\n<p>De mani\u00e8re g\u00e9n\u00e9rale, il faut savoir que le CPF (pour <strong>Compte Personnel de Formation<\/strong>) est le digne successeur du <a href=\"https:\/\/edusign.fr\/blog\/transfert-dif-vers-cpf-les-etapes-a-suivre\/\" data-type=\"post\" data-id=\"6847\" target=\"_blank\" rel=\"noopener\">DIF<\/a> (le Droit Individuel \u00e0 la Formation). Les salari\u00e9s \u00e0 temps plein, les salari\u00e9s \u00e0 temps partiel ainsi que les travailleurs ind\u00e9pendants y ont pleinement acc\u00e8s.&nbsp;<\/p>\n\n\n\n<p>Le <strong>principe de la mutualisation<\/strong> r\u00e9git son fonctionnement. Cela signifie que les employeurs et les ind\u00e9pendants payent des cotisations destin\u00e9es \u00e0 financer la formation professionnelle, des cotisations permettant ensuite de cr\u00e9diter les droits CPF des travailleurs. Il s\u2019agit donc d\u2019une technique privil\u00e9gi\u00e9e de mise en commun de moyens pour financer les diverses formations professionnelles en mesure d\u2019int\u00e9resser les travailleurs. Ces derni\u00e8res vont de la validation des acquis de l\u2019exp\u00e9rience \u00e0 l\u2019acquisition de nouvelles comp\u00e9tences, en passant par des formations en langues \u00e9trang\u00e8res ou encore l\u2019obtention du permis de conduire.<\/p>\n\n\n\n<p><br>Et le CPF suit chaque travailleur tout au long de sa carri\u00e8re professionnelle, \u00e0 partir de l\u2019\u00e2ge de 16 ans et <strong>jusqu\u2019\u00e0 la retraite<\/strong> ! Condition : avoir une activit\u00e9 professionnelle se tenant <strong>au moins \u00e0 mi-temps.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-center\"><img fetchpriority=\"high\" decoding=\"async\" width=\"548\" height=\"365\" src=\"https:\/\/lh4.googleusercontent.com\/NHC1RMLZhcTPPFfPF5Xa-mbSG_cfWQGxGmU6suk_vrzXMQk2ZmcXj-Bzxtz0We9_O8e_HFkcxjFcg_0ZrCbEmDC5GHYdIB0QbEqufmPHugCBjG_QwscwqsA2ND1T9Ib3YpN9rMPGj7-lYIfYd5ARAaQTcY-t9Uoi5q8cEPXX7QqyVlsITUXj2UCU26qkgvlI-p9JvgrYHQ\" alt=\"Image\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qui peut abonder, alimenter un compte CPF ?<\/h2>\n\n\n\n<p>Ce qu\u2019il faut savoir, c\u2019est qu\u2019un compte CPF peut \u00eatre aliment\u00e9 de diff\u00e9rentes mani\u00e8res. Le principal facteur \u00e0 prendre en compte est avant tout le <strong>statut du travailleur<\/strong> ainsi que le <strong>temps de travail effectif<\/strong>. S\u2019il s\u2019agit d\u2019un salari\u00e9 sous contrat, d\u2019un travailleur ind\u00e9pendant dit freelance, ou encore d\u2019un demandeur d\u2019emploi, le sc\u00e9nario ne sera pas le m\u00eame.&nbsp;<\/p>\n\n\n\n<p>Voici les trois principales cat\u00e9gories \u00e0 conna\u00eetre s\u2019agissant de l\u2019abondement des comptes CPF !&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les salari\u00e9s<\/h3>\n\n\n\n<p>Si vous \u00eates salari\u00e9, l\u2019abondement de vos droits CPF est assur\u00e9 par votre <strong>employeur<\/strong>. En se connectant sur l&rsquo;Espace des employeurs et des financeurs (EDEF), votre employeur peut ainsi proc\u00e9der \u00e0 l\u2019abondement de votre compte CPF en quelques \u00e9tapes simples. La principale chose \u00e0 retenir, c\u2019est que votre employeur a surtout la libert\u00e9 de choisir les <strong>modalit\u00e9s<\/strong> ainsi que le <strong>montant de l\u2019abondement<\/strong>.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Tout employeur a donc la possibilit\u00e9 de proc\u00e9der \u00e0 l\u2019abondement du compte CPF de son salari\u00e9 de lui-m\u00eame, ou bien sur demande expresse du salari\u00e9. \u00c0 cela s\u2019ajoutent d\u2019autres types de dotations, telles que :&nbsp;<\/p>\n\n\n\n<ul>\n<li>les <strong>droits suppl\u00e9mentaires<\/strong> pr\u00e9vus par un <strong>accord collectif<\/strong>,<\/li>\n\n\n\n<li>la dotation obligatoire de <strong>3000 \u20ac<\/strong> applicable aux <strong>salari\u00e9s licenci\u00e9s<\/strong> pour refus d&rsquo;un accord de performance collectif,<\/li>\n<\/ul>\n\n\n\n<p>et enfin ce que l\u2019on appelle les <strong>droits correctifs<\/strong>, c\u2019est-\u00e0-dire ceux s\u2019appliquant aux entreprises de plus de 50 salari\u00e9s dans lesquelles l\u2019employeur n\u2019a pas respect\u00e9 son obligation d\u2019assurer des entretiens professionnels pendant 6 ans.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Travailleurs ind\u00e9pendants et Fonds d\u2019Assurance de Formation<\/h3>\n\n\n\n<p>Le CPF est r\u00e9put\u00e9 ne b\u00e9n\u00e9ficier qu\u2019aux travailleurs salari\u00e9s, or cela est totalement faux. Les travailleurs ind\u00e9pendants, \u00e9galement appel\u00e9s freelances ou auto-entrepreneurs, peuvent \u00e9galement y pr\u00e9tendre. Toutefois, une petite nuance doit \u00eatre relev\u00e9e concernant le mode de cotisation.&nbsp;<\/p>\n\n\n\n<p>Contrairement \u00e0 des salari\u00e9s dont l\u2019abondement CPF est assur\u00e9 par l\u2019employeur, des travailleurs ind\u00e9pendants financent leurs droits CPF en cotisant aupr\u00e8s du <strong>Fonds d\u2019Assurance de Formation<\/strong>. Pour chaque ann\u00e9e d\u2019activit\u00e9 d\u00e9clar\u00e9e, les travailleurs ind\u00e9pendants de toute cat\u00e9gorie voient ainsi leur compte CPF \u00eatre abond\u00e9 de 500 \u20ac par an.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Le cas particulier des demandeurs d\u2019emploi et de P\u00f4le Emploi<\/h3>\n\n\n\n<p>Enfin, abordons le cas particulier des personnes en recherche d\u2019emploi. Si vous n\u2019avez pas d\u2019emploi, mais que vous \u00eates demandeur d\u2019emploi et que vous avez trouv\u00e9 une <strong>formation<\/strong> qui serait parfaite pour vous <strong>aider \u00e0 r\u00e9int\u00e9grer le monde du travail<\/strong>, alors P\u00f4le Emploi peut vous donner un coup de pouce. A condition bien s\u00fbr que vous fassiez preuve d\u2019assiduit\u00e9 dans le suivi de votre formation.&nbsp;<\/p>\n\n\n\n<p>En effet, lorsque vos droits CPF ne sont pas assez \u00e9lev\u00e9s pour financer la formation envisag\u00e9e, <strong>P\u00f4le Emploi<\/strong> est en mesure de verser une sorte de <strong>financement compl\u00e9mentaire<\/strong> vous donnant acc\u00e8s \u00e0 cette formation tant d\u00e9sir\u00e9e. Pour cela, directement depuis votre compte CPF, s\u00e9lectionnez la formation concern\u00e9e (cette derni\u00e8re devant bien s\u00fbr \u00eatre \u00e9ligible au CPF), puis vous n\u2019aurez plus qu\u2019\u00e0 choisir de b\u00e9n\u00e9ficier d&rsquo;un abondement de la part de P\u00f4le Emploi.<\/p>\n\n\n\n<p><br>D\u2019un point de vue des d\u00e9lais, gardez \u00e0 l\u2019esprit que votre demande d\u2019abondement par P\u00f4le Emploi doit \u00eatre effectu\u00e9e dans un <strong>d\u00e9lai de 15 jours minimum avant le d\u00e9but de votre formation<\/strong>, P\u00f4le Emploi disposant ensuite d\u2019un d\u00e9lai de 10 jours afin de vous communiquer sa r\u00e9ponse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le CPF est un sujet tr\u00e8s r\u00e9guli\u00e8rement abord\u00e9 dans l\u2019actualit\u00e9, en particulier en p\u00e9riode de crise lorsque tout un chacun chercher \u00e0 peaufiner ses comp\u00e9tences professionnelles, ou \u00e0 se former \u00e0 un nouveau poste. Les enjeux des formations professionnelles sont importants, mais ce qui nous int\u00e9resse ici, c\u2019est surtout la mani\u00e8re dont les comptes CPF [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6881,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":""},"categories":[13],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/posts\/6880"}],"collection":[{"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/comments?post=6880"}],"version-history":[{"count":0,"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/posts\/6880\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/media\/6881"}],"wp:attachment":[{"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/media?parent=6880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/categories?post=6880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edusign.com\/fr\/wp-json\/wp\/v2\/tags?post=6880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}